{"id":3,"count":3,"description":"","link":"https:\/\/www.sougiareflexology.gr\/el\/category\/therapy\/","name":"\u0398\u03b5\u03c1\u03b1\u03c0\u03b5\u03af\u03b5\u03c2","slug":"therapy","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.sougiareflexology.gr\/el\/wp-json\/wp\/v2\/categories\/3"}],"collection":[{"href":"https:\/\/www.sougiareflexology.gr\/el\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.sougiareflexology.gr\/el\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.sougiareflexology.gr\/el\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}